{"id":95,"date":"2009-02-07T18:48:04","date_gmt":"2009-02-07T17:48:04","guid":{"rendered":"http:\/\/wlochata-pasja.home.pl\/www\/?p=95"},"modified":"2018-03-19T10:31:57","modified_gmt":"2018-03-19T09:31:57","slug":"dzentelmen-do-wynajecia-uslugi-reproduktora","status":"publish","type":"post","link":"https:\/\/www.wlochata-pasja.com.pl\/de\/australisches-labradoodle\/labradoodle-wlochatej-pasji\/gentleman-for-hire-gestut-service\/","title":{"rendered":"GENTLEMAN ZU VERMIETEN (STUDIENDIENSTLEISTUNGEN)"},"content":{"rendered":"<div id=\"attachment_3363\" style=\"width: 211px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.wlochata-pasja.com.pl\/plik\/dostojny-1.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3363\" class=\"wp-image-3363 size-medium\" src=\"https:\/\/www.wlochata-pasja.com.pl\/plik\/dostojny-1-201x300.jpg\" alt=\"Rutlands Black Onyxe \u2013 Australisches Labradoodle\" width=\"201\" height=\"300\" srcset=\"https:\/\/www.wlochata-pasja.com.pl\/plik\/dostojny-1-201x300.jpg 201w, https:\/\/www.wlochata-pasja.com.pl\/plik\/dostojny-1-768x1147.jpg 768w, https:\/\/www.wlochata-pasja.com.pl\/plik\/dostojny-1-686x1024.jpg 686w, https:\/\/www.wlochata-pasja.com.pl\/plik\/dostojny-1.jpg 778w\" sizes=\"(max-width: 201px) 100vw, 201px\" \/><\/a><p id=\"caption-attachment-3363\" class=\"wp-caption-text\">Rutlands Black Onyxe \u2013 Australischer Labradoodle<\/p><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><br \/>\n<\/span><\/p>\n<p>Name: Rutlands Black Onyxe<\/p>\n<p>Rasse: Australischer Labradoodle<\/p>\n<p>Registrierungsnummer: AES-F10002C<\/p>\n<p>Schwarze Farbe<\/p>\n<p>Fell: \u201elockig\u201c lockig<\/p>\n<p>Gr\u00f6\u00dfe: Mittel (Standard- und mittelgro\u00dfe Welpen)<\/p>\n<p>Tests:<\/p>\n<p>Prcd-PRA: KLAR<\/p>\n<p>H\u00fcftgelenke: ausgezeichnet (Ergebnisse liegen in der Zucht vor)<\/p>\n<p>Ellenbogen: ausgezeichnet (Ergebnisse liegen in der Zucht vor)<\/p>\n<p>DNA-Profil: 21827 1<\/p>\n<p>Vater: Rutlands Black Onyx<\/p>\n<p>Mutter: Flamingo Isabella of Rutlands<\/p>\n<p><strong><em>HINWEIS: Rutland Black Onyxe ist nur f\u00fcr die Verpaarung von ASD Australian Labradoodles vorgesehen, die von der Organisation registriert sind <strong>ALPHA EUROPA<\/strong>. Nur so und nach einer gr\u00fcndlichen \u00dcberpr\u00fcfung des Inzuchtanteils (in der Rutlands-Linie in Hairy Passion erlauben wir maximal 3%) k\u00f6nnen wir diese Linie sauber halten. Jeder Z\u00fcchter ist verpflichtet, Original-DNA-Tests vorzulegen, die die Herkunft der H\u00fcndin best\u00e4tigen. Die Mikrochip-Nummer muss mit der in den DNA-Aufzeichnungen \u00fcbereinstimmen. Jeder Z\u00fcchter ist verpflichtet, die von ALFA EUROPE ausgestellte Original-Ahnentafel vorzulegen.<\/em><\/strong><\/p>\n<p>Z\u00fcchter anderer Generationen als des ASD Australian Labradoodle (z. B. F1, F1B, F2, F2B) und Z\u00fcchter, die nicht der ALFA EUROPE-Organisation angeschlossen sind, werden gebeten, uns bez\u00fcglich der Zuchtdienste nicht zu kontaktieren.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>Rutlands WH Lil Donnan schlie\u00dft sich ebenfalls der Gruppe der zuk\u00fcnftigen Deckr\u00fcden an, es handelt sich um einen australischen Labradoodle in Miniaturgr\u00f6\u00dfe mit einem sehr seltenen \u201eFactored\u201c-Fell. Das bedeutet, dass einzelne Teile seines K\u00f6rpers (Pfoten, Kopf) verblassen und zu einer Karamellfarbe (braunes und gebr\u00e4untes Karamell) aufhellen.<br \/>\nIn der Praxis bedeutet dies, dass in Kombination mit einer H\u00fcndin \u00e4hnlicher Farbe zweifarbige Welpen geboren werden.<\/p>\n<p>Hier ist ein Bild von Donnan:<\/p>\n<div id=\"attachment_1988\" style=\"width: 160px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.wlochata-pasja.com.pl\/de\/plik\/Australijski-Labradoodle-Donnan-Wlochata-Pasja.jpg\/\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1988\" class=\"size-thumbnail wp-image-1988\" title=\"Australischer Labradoodle Donnan\" src=\"http:\/\/www.wlochata-pasja.com.pl\/plik\/Australijski-Labradoodle-Donnan-Wlochata-Pasja-150x150.jpg\" alt=\"Australischer Labradoodle Donnan\" width=\"150\" height=\"150\" \/><\/a><p id=\"caption-attachment-1988\" class=\"wp-caption-text\">Australischer Labradoodle Donnan<\/p><\/div>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>Haarige Leidenschaft<br \/>\nAustralischer Labradoodle-Zwinger in Polen<br \/>\nErster australischer Labradoodle in Polen<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Name: Rutlands Black Onyxe Rasse: Australian Labradoodle Registrierungsnummer: AES-F10002C Farbe: Schwarz Fell: \u201elockig\u201c lockig Gr\u00f6\u00dfe: Mittel (Standard- und mittelgro\u00dfe Welpen) Tests: Prcd-PRA: CLEAR H\u00fcftgelenke: ausgezeichnet (Ergebnisse in der Zucht verf\u00fcgbar). ) Ellenbogengelenke: ausgezeichnet (Ergebnisse in der Zucht verf\u00fcgbar) DNA-Profil: 21827 1 Vater: Rutlands Black Onyx Mutter: Flaming Isabella of Rutlands HINWEIS: Rutland Black [\u2026]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/posts\/95"}],"collection":[{"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/comments?post=95"}],"version-history":[{"count":0,"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/posts\/95\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/media?parent=95"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/categories?post=95"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wlochata-pasja.com.pl\/de\/wp-json\/wp\/v2\/tags?post=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}